{"id":82,"date":"2021-04-24T11:23:55","date_gmt":"2021-04-24T11:23:55","guid":{"rendered":"http:\/\/nanotechshimi.ir\/blog\/?p=82"},"modified":"2021-07-31T09:52:46","modified_gmt":"2021-07-31T09:52:46","slug":"%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9","status":"publish","type":"post","link":"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/","title":{"rendered":"\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_31_1 counter-hierarchy counter-decimal ez-toc-grey\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" style=\"display: none;\"><label for=\"item\" aria-label=\"Table of Content\"><i class=\"ez-toc-glyphicon ez-toc-icon-toggle\"><\/i><\/label><input type=\"checkbox\" id=\"item\"><\/a><\/span><\/div>\n<nav><ul class=\"ez-toc-list ez-toc-list-level-1\"><li class=\"ez-toc-page-1 ez-toc-heading-level-1\"><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%AE%D9%88%D8%A7%D8%B5_%D9%85%D9%87%D9%85_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9\" title=\"\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9\">\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9<\/a><ul class=\"ez-toc-list-level-2\"><li class=\"ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%AE%D9%88%D8%A7%D8%B5_%D8%A8%D8%A7%D8%B1%D8%B2_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%AF%D8%B1_%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%D9%BE%D8%B2%D8%B4%DA%A9%DB%8C_%D9%88_%D8%AF%D8%A7%D8%B1%D9%88%D8%B3%D8%A7%D8%B2%DB%8C\" title=\"\u062e\u0648\u0627\u0635 \u0628\u0627\u0631\u0632 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u067e\u0632\u0634\u06a9\u06cc \u0648 \u062f\u0627\u0631\u0648\u0633\u0627\u0632\u06cc\">\u062e\u0648\u0627\u0635 \u0628\u0627\u0631\u0632 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u067e\u0632\u0634\u06a9\u06cc \u0648 \u062f\u0627\u0631\u0648\u0633\u0627\u0632\u06cc<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%AE%D9%88%D8%A7%D8%B5_%D9%85%D9%87%D9%85_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%AF%D8%B1_%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%D8%B4%DB%8C%D8%B4%D9%87_%D8%B3%D8%A7%D8%B2%DB%8C\" title=\"\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0634\u0647 \u0633\u0627\u0632\u06cc\">\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0634\u0647 \u0633\u0627\u0632\u06cc<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%AD%D9%81%D8%B8_%D9%88_%D9%86%DA%AF%D9%87%D8%AF%D8%A7%D8%B1%DB%8C_%DA%86%D9%88%D8%A8_%D9%87%D8%A7_%D8%A8%D9%87_%D9%88%D8%B3%DB%8C%D9%84%D9%87_%D8%A2%D9%86\" title=\"\u062d\u0641\u0638 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0686\u0648\u0628 \u0647\u0627 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0622\u0646\">\u062d\u0641\u0638 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0686\u0648\u0628 \u0647\u0627 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0622\u0646<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D9%86%D9%82%D8%B4_%D8%A2%D9%86_%D8%AF%D8%B1_%D8%B3%D8%A7%D8%AE%D8%AA_%D8%B1%D9%88%D8%A7%D9%86_%DA%A9%D9%86%D9%86%D8%AF%D9%87_%D9%87%D8%A7\" title=\"\u0646\u0642\u0634 \u0622\u0646 \u062f\u0631 \u0633\u0627\u062e\u062a \u0631\u0648\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0647\u0627\">\u0646\u0642\u0634 \u0622\u0646 \u062f\u0631 \u0633\u0627\u062e\u062a \u0631\u0648\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0647\u0627<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%AE%D9%88%D8%A7%D8%B5_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%AF%D8%B1_%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%B3%D8%B7%D8%AD_%DA%A9%DB%8C%D9%81%DB%8C_%D9%81%D8%B1%D8%A7%D9%88%D8%B1%D8%AF%D9%87_%D9%87%D8%A7%DB%8C_%DA%A9%D8%B4%D8%A7%D9%88%D8%B1%D8%B2%DB%8C\" title=\"\u062e\u0648\u0627\u0635 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0637\u062d \u06a9\u06cc\u0641\u06cc \u0641\u0631\u0627\u0648\u0631\u062f\u0647 \u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc\">\u062e\u0648\u0627\u0635 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0637\u062d \u06a9\u06cc\u0641\u06cc \u0641\u0631\u0627\u0648\u0631\u062f\u0647 \u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%AE%D9%88%D8%A7%D8%B5_%D8%A7%DB%8C%D9%86_%D9%85%D8%A7%D8%AF%D9%87_%D8%B4%D9%80%D9%80%DB%8C%D9%85%DB%8C%D8%A7%DB%8C%DB%8C_%D8%AF%D8%B1_%D8%B5%D9%86%D8%B9%D8%AA_%D8%B3%D8%B1%D8%A7%D9%85%DB%8C%DA%A9_%D8%B3%D8%A7%D8%B2%DB%8C\" title=\"\u062e\u0648\u0627\u0635 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u0635\u0646\u0639\u062a \u0633\u0631\u0627\u0645\u06cc\u06a9 \u0633\u0627\u0632\u06cc\">\u062e\u0648\u0627\u0635 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u0635\u0646\u0639\u062a \u0633\u0631\u0627\u0645\u06cc\u06a9 \u0633\u0627\u0632\u06cc<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D8%A7%DB%8C%D9%86_%D9%85%D8%A7%D8%AF%D9%87_%D8%B4%D9%80%D9%80%DB%8C%D9%85%DB%8C%D8%A7%DB%8C%DB%8C_%D8%AF%D8%B1_%D8%AD%D8%B4%D8%B1%D9%87_%DA%A9%D8%B4%DB%8C\" title=\"\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u062d\u0634\u0631\u0647 \u06a9\u0634\u06cc\">\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u062d\u0634\u0631\u0647 \u06a9\u0634\u06cc<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%B3%D8%A7%D8%AE%D8%AA_%D9%85%D9%88%D8%A7%D8%AF_%D8%B6%D8%AF_%D8%A2%D8%AA%D8%B4_%D8%A8%D9%87_%D9%88%D8%B3%DB%8C%D9%84%D9%87_%D8%A7%DB%8C%D9%86_%D9%85%D8%A7%D8%AF%D9%87_%D8%B4%D9%80%D9%80%DB%8C%D9%85%DB%8C%D8%A7%DB%8C%DB%8C\" title=\"\u0633\u0627\u062e\u062a \u0645\u0648\u0627\u062f \u0636\u062f \u0622\u062a\u0634 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc\">\u0633\u0627\u062e\u062a \u0645\u0648\u0627\u062f \u0636\u062f \u0622\u062a\u0634 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%AE%D9%88%D8%A7%D8%B5_%D9%85%D9%87%D9%85_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%AF%D8%B1_%D9%85%D9%88%D8%A7%D8%AF_%D8%BA%D8%B0%D8%A7%DB%8C%DB%8C\" title=\"\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc\">\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc<\/a><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%AE%D9%88%D8%A7%D8%B5_%D8%B6%D8%AF_%D8%B3%D8%B1%D8%B7%D8%A7%D9%86%DB%8C_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9\" title=\"\u062e\u0648\u0627\u0635 \u0636\u062f \u0633\u0631\u0637\u0627\u0646\u06cc \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9\">\u062e\u0648\u0627\u0635 \u0636\u062f \u0633\u0631\u0637\u0627\u0646\u06cc \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9<\/a><ul class=\"ez-toc-list-level-3\"><li class=\"ez-toc-heading-level-3\"><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%A7%DB%8C%D9%86_%D9%86%D9%88%D8%B9_%D9%85%D8%A7%D8%AF%D9%87_%D8%B4%DB%8C%D9%85%DB%8C%D8%A7%DB%8C%DB%8C_%D9%88_%D9%82%D8%B7%D8%B1%D9%87_%DA%AF%D9%88%D8%B4\" title=\"\u0627\u06cc\u0646 \u0646\u0648\u0639 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0648 \u0642\u0637\u0631\u0647 \u06af\u0648\u0634\">\u0627\u06cc\u0646 \u0646\u0648\u0639 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0648 \u0642\u0637\u0631\u0647 \u06af\u0648\u0634<\/a><\/li><\/ul><\/li><li class=\"ez-toc-page-1 ez-toc-heading-level-2\"><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#%D8%A8%D8%B9%D8%B6%DB%8C_%D8%A7%D8%B2_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%87%D8%A7%DB%8C_%D8%B9%D9%85%D8%AF%D9%87_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%B9%D8%A8%D8%A7%D8%B1%D8%AA%D9%86%D8%AF_%D8%A7%D8%B2\" title=\"\u0628\u0639\u0636\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0628\u0631\u062f \u0647\u0627\u06cc \u0639\u0645\u062f\u0647 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:\">\u0628\u0639\u0636\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0628\u0631\u062f \u0647\u0627\u06cc \u0639\u0645\u062f\u0647 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h1 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%A7%D8%B5_%D9%85%D9%87%D9%85_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9\"><\/span><span style=\"color: #ff9900;\">\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9<\/span><span class=\"ez-toc-section-end\"><\/span><\/h1>\n<p style=\"text-align: justify;\">\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 <strong><span style=\"color: #ff9900;\"><a style=\"color: #ff9900;\" href=\"http:\/\/nanotechshimi.ir\/%d8%a7%d8%b3%db%8c%d8%af%d9%87%d8%a7\/\" target=\"_blank\" rel=\"noopener\">\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9<\/a><\/span><\/strong> \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639\u060c\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u06cc\u06a9 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0634\u0646\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0635\u0648\u0631\u062a \u062c\u0627\u0645\u062f \u0647\u0645 \u0645\u06cc \u0628\u0627\u0634\u062f. \u0631\u0646\u06af \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0633\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u060c \u062f\u0627\u0631\u0627\u06cc \u0637\u0639\u0645\u06cc \u062a\u0644\u062e \u0648 \u0628\u06cc \u0628\u0648 \u0645\u06cc \u0628\u0627\u0634\u062f.\u200c \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0645\u0639\u0645\u0648\u0644\u0627 \u0627\u0633\u06cc\u062f\u06cc \u0636\u0639\u06cc\u0641 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc \u0622\u06cc\u062f \u0648 \u0646\u0645\u06a9 \u0647\u0627\u06cc \u062d\u0627\u0648\u06cc \u0633\u062f\u06cc\u0645 \u062f\u0627\u0631\u062f \u06a9\u0647 \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0627\u0632 \u062a\u0644\u0641\u06cc\u0642\u0627\u062a \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0631\u0627 \u0628\u0627 \u062f\u06cc\u06af\u0631 \u0639\u0646\u0627\u0635\u0631 \u062a\u0644\u0641\u06cc\u0642 \u0645\u06cc \u06a9\u0646\u0646\u062f.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%A7%D8%B5_%D8%A8%D8%A7%D8%B1%D8%B2_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%AF%D8%B1_%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%D9%BE%D8%B2%D8%B4%DA%A9%DB%8C_%D9%88_%D8%AF%D8%A7%D8%B1%D9%88%D8%B3%D8%A7%D8%B2%DB%8C\"><\/span><span style=\"color: #ff9900;\">\u062e\u0648\u0627\u0635 \u0628\u0627\u0631\u0632 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u067e\u0632\u0634\u06a9\u06cc \u0648 \u062f\u0627\u0631\u0648\u0633\u0627\u0632\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0627\u0632 \u0639\u0645\u062f\u0647 \u062a\u0631\u06cc\u0646 \u062e\u0648\u0627\u0635 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0622\u0646\u062a\u06cc \u0628\u0627\u06a9\u062a\u0631\u06cc \u0648 \u0622\u0646\u062a\u06cc \u0642\u0627\u0631\u0686 \u0628\u0648\u062f\u0646 \u0622\u0646 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0686\u0646\u06cc\u0646 \u0645\u0634\u062e\u0635\u0647 \u0647\u0627\u06cc\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0633\u0628\u0628 \u0634\u062f\u0647 \u062a\u0627 \u062f\u0631 \u067e\u0632\u0634\u06a9\u06cc \u0628\u06a9\u0627\u0631 \u06af\u06cc\u0631\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0627\u0632 \u0622\u0646 \u0634\u0648\u062f \u0648 \u0627\u0646\u0631\u0627 \u0647\u0645\u0627\u0646\u0646\u062f \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u0631\u0627\u06cc \u0639\u0641\u0648\u0646\u062a \u0632\u062f\u0627\u06cc\u06cc \u06a9\u0644\u06cc\u0647 \u0627\u0639\u0636\u0627 \u0628\u062f\u0646 \u0628\u0634\u0646\u0627\u0633\u0646\u062f.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/nanotechshimi.ir\/blog\/wp-content\/uploads\/2021\/04\/\u062e\u0648\u0627\u0635-\u0645\u0647\u0645-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-.jpg\"><img loading=\"lazy\" class=\"wp-image-85 size-full aligncenter\" src=\"http:\/\/nanotechshimi.ir\/blog\/wp-content\/uploads\/2021\/04\/\u062e\u0648\u0627\u0635-\u0645\u0647\u0645-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-.jpg\" alt=\"\" width=\"600\" height=\"473\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u062e\u06cc\u0644\u06cc \u0627\u0632 \u062f\u0627\u0631\u0648\u0647\u0627 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0645\u06cc\u0632\u0627\u0646 \u06a9\u0645\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0631\u0627 \u062f\u0631 \u062e\u0648\u062f \u062f\u0627\u0631\u0646\u062f \u0648 \u067e\u0632\u0634\u06a9\u0627\u0646 \u0648 \u0645\u062a\u062e\u0635\u0635\u0627\u0646 \u0645\u0639\u0645\u0648\u0644\u0627 \u0622\u0646\u0631\u0627 \u0628\u0631\u0627\u06cc \u0645\u0633\u0627\u0626\u0644\u06cc \u0646\u0638\u06cc\u0631 \u0639\u0641\u0648\u0646\u062a \u0632\u062f\u0627\u06cc\u06cc\u060c \u06a9\u0646\u062a\u0631\u0644 PH \u0648 \u0628\u0631\u0637\u0631\u0641 \u0646\u0645\u0648\u062f\u0646 \u062e\u0634\u06a9\u06cc \u0686\u0634\u0645 \u062a\u062c\u0648\u06cc\u0632 \u0645\u06cc \u06a9\u0646\u0646\u062f.\u200c \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0628\u0631\u0637\u0631\u0641 \u06a9\u0631\u062f\u0646 \u0639\u0641\u0648\u0646\u062a \u0648\u0627\u0698\u06cc\u0646\u0627\u0644 \u0646\u06cc\u0632 \u06a9\u0627\u0631\u0628\u0631\u062f \u0639\u0645\u062f\u0647 \u0627\u06cc \u062f\u0627\u0631\u062f. \u0627\u0641\u0631\u0648\u0646 \u0628\u0631 \u0627\u06cc\u0646 \u062f\u0642\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u062c\u0627\u0632\u0647 \u0628\u06a9\u0627\u0631\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u062f\u0631\u0645\u0627\u0646 \u062a\u0646\u0647\u0627 \u0628\u0647 \u062a\u062c\u0648\u06cc\u0632 \u067e\u0632\u0634\u06a9 \u0627\u0645\u06a9\u0627\u0646 \u067e\u0630\u06cc\u0631 \u0627\u0633\u062a.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%A7%D8%B5_%D9%85%D9%87%D9%85_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%AF%D8%B1_%D8%B5%D9%86%D8%A7%DB%8C%D8%B9_%D8%B4%DB%8C%D8%B4%D9%87_%D8%B3%D8%A7%D8%B2%DB%8C\"><\/span><span style=\"color: #ff9900;\">\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u0634\u06cc\u0634\u0647 \u0633\u0627\u0632\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0633\u0627\u062e\u062a \u062e\u06cc\u0644\u06cc \u0627\u0632 \u0641\u0631\u0627\u0648\u0631\u062f\u0647 \u0647\u0627\u06cc \u0634\u06cc\u0634\u0647 \u0627\u06cc \u06a9\u0627\u0631\u0627\u06cc\u06cc \u062e\u0627\u0635 \u0648 \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f\u06cc \u062f\u0627\u0631\u062f. \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u067e\u0631\u0648\u0633\u0647 \u0633\u0627\u062e\u062a \u0634\u06cc\u0634\u0647 \u0646\u0642\u0634 \u0686\u0634\u0645\u06af\u06cc\u0631\u06cc \u062f\u0627\u0631\u062f \u0686\u0631\u0627 \u06a9\u0647 \u0627\u06a9\u062b\u0631 \u0634\u06cc\u0634\u0647 \u0647\u0627\u06cc \u0622\u0632\u0645\u0627\u06cc\u0634\u06af\u0627\u0647\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u0634\u0648\u06a9 \u0647\u0627\u06cc \u06af\u0631\u0645\u0627\u06cc\u0634\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f \u0639\u0627\u06cc\u0642 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u0648 \u0627\u0633\u062a\u0642\u0627\u0645\u062a \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0645\u062a\u0634\u06a9\u0644 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u06cc \u0628\u0627\u0634\u0646\u062f. \u062f\u0631 \u0633\u0627\u062e\u062a \u0648\u0631\u0642\u0647 \u0647\u0627\u06cc \u0634\u06cc\u0634\u0647 \u0627\u06cc \u0645\u062d\u06a9\u0645 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u062f\u0631 \u0633\u0627\u062e\u062a \u0634\u06cc\u0634\u0647 \u0647\u0627\u06cc \u0646\u0627\u0631\u0633\u0627\u0646\u0627\u06cc \u0634\u06cc\u0634\u0647 \u0627\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0628\u0631\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AD%D9%81%D8%B8_%D9%88_%D9%86%DA%AF%D9%87%D8%AF%D8%A7%D8%B1%DB%8C_%DA%86%D9%88%D8%A8_%D9%87%D8%A7_%D8%A8%D9%87_%D9%88%D8%B3%DB%8C%D9%84%D9%87_%D8%A2%D9%86\"><\/span><span style=\"color: #ff9900;\">\u062d\u0641\u0638 \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0686\u0648\u0628 \u0647\u0627 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0622\u0646<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0686\u0648\u0628 \u0647\u0627 \u0628\u0647 \u0634\u06a9\u0644 \u062e\u0627\u0645 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0686\u0634\u0645\u06af\u06cc\u0631\u06cc \u062f\u0627\u0631\u062f \u0648 \u0627\u06cc\u0646 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0637\u06cc \u0633\u0627\u0644\u06cc\u0627\u0646 \u0645\u062f\u06cc\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0631\u0648\u0646\u0642 \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u06cc\u06a9 \u0645\u0648\u0644\u0641\u0647 \u0636\u062f \u062d\u0634\u0631\u0647 \u0648 \u0636\u062f \u0642\u0627\u0631\u0686 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc \u0622\u06cc\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%86%D9%82%D8%B4_%D8%A2%D9%86_%D8%AF%D8%B1_%D8%B3%D8%A7%D8%AE%D8%AA_%D8%B1%D9%88%D8%A7%D9%86_%DA%A9%D9%86%D9%86%D8%AF%D9%87_%D9%87%D8%A7\"><\/span><span style=\"color: #ff9900;\">\u0646\u0642\u0634 \u0622\u0646 \u062f\u0631 \u0633\u0627\u062e\u062a \u0631\u0648\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0647\u0627<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u067e\u0631\u0648\u0633\u0647 \u0633\u0627\u062e\u062a \u0631\u0648\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0622\u0628 \u062d\u0644 \u0634\u0648\u0646\u062f\u0647 \u0646\u0642\u0634 \u0645\u0637\u0628\u0648\u0639 \u06a9\u0646\u0646\u062f\u06af\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0628\u0647 \u06a9\u0627\u0631 \u0628\u0631\u062f\u0647 \u0645\u06cc \u0634\u0648\u0646\u062f \u062a\u0627 \u0633\u0628\u0628 \u0627\u0633\u062a\u0642\u0627\u0645\u062a \u0628\u06cc\u0648\u0644\u0648\u0698\u06cc\u06a9 \u0628\u0627\u0644\u0627 \u0648 \u0627\u0633\u062a\u0642\u0627\u0645\u062a PH \u0634\u0648\u0646\u062f.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%A7%D8%B5_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%AF%D8%B1_%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%B3%D8%B7%D8%AD_%DA%A9%DB%8C%D9%81%DB%8C_%D9%81%D8%B1%D8%A7%D9%88%D8%B1%D8%AF%D9%87_%D9%87%D8%A7%DB%8C_%DA%A9%D8%B4%D8%A7%D9%88%D8%B1%D8%B2%DB%8C\"><\/span><span style=\"color: #ff9900;\">\u062e\u0648\u0627\u0635 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0637\u062d \u06a9\u06cc\u0641\u06cc \u0641\u0631\u0627\u0648\u0631\u062f\u0647 \u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f\u06cc \u062f\u0631 \u067e\u06cc\u0634\u0631\u0641\u062a \u0633\u0637\u062d \u06a9\u06cc\u0641\u06cc \u0641\u0631\u0627\u0648\u0631\u062f\u0647 \u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u062f\u0627\u0631\u062f \u0648 \u0628\u0627 \u062a\u0642\u0648\u06cc\u062a \u0628\u062e\u0634\u06cc \u0628\u0647 \u062c\u062f\u0627\u0631\u0647 \u0647\u0627\u06cc \u0633\u0644\u0648\u0644\u06cc \u06af\u06cc\u0627\u0647\u0627\u0646 \u0633\u0628\u0628 \u0628\u0627\u0644\u0627 \u0631\u0641\u062a\u0646 \u0645\u0642\u062f\u0627\u0631 \u0631\u0648\u0627\u0644 \u062c\u0630\u0628 \u0648 \u0641\u062a\u0648\u0633\u0646\u062a\u0632 \u0645\u06cc \u0634\u0648\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0633\u0628\u0628 \u062a\u06a9\u062b\u06cc\u0631 \u0631\u0634\u062f \u0641\u0631\u0622\u0648\u0631\u062f\u0647 \u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0645\u06cc \u0634\u0648\u062f \u0686\u0648\u0646 \u062a\u0628\u062e\u06cc\u0631 \u0628\u0631\u06af \u0647\u0627\u06cc \u06af\u06cc\u0627\u0647\u0627\u0646 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc \u062f\u0647\u062f \u0632\u06cc\u0631\u0627 \u06a9\u0647 \u0633\u0628\u0628 \u062a\u0639\u0627\u062f\u0644 \u0633\u0627\u0632\u06cc \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0645\u06cc \u0634\u0648\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%A7%D8%B5_%D8%A7%DB%8C%D9%86_%D9%85%D8%A7%D8%AF%D9%87_%D8%B4%D9%80%D9%80%DB%8C%D9%85%DB%8C%D8%A7%DB%8C%DB%8C_%D8%AF%D8%B1_%D8%B5%D9%86%D8%B9%D8%AA_%D8%B3%D8%B1%D8%A7%D9%85%DB%8C%DA%A9_%D8%B3%D8%A7%D8%B2%DB%8C\"><\/span><span style=\"color: #ff9900;\">\u062e\u0648\u0627\u0635 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u0635\u0646\u0639\u062a \u0633\u0631\u0627\u0645\u06cc\u06a9 \u0633\u0627\u0632\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0627\u0632 \u0639\u0645\u062f\u0647 \u062a\u0631\u06cc\u0646 \u062e\u0648\u0627\u0635 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0635\u0646\u0639\u062a \u0633\u0631\u0627\u0645\u06cc\u06a9 \u0633\u0627\u0632\u06cc \u0627\u0634\u0627\u0631\u0647 \u0646\u0645\u0648\u062f \u0686\u0631\u0627 \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0645\u0648\u062b\u0631 \u0648 \u0633\u0648\u062f\u0645\u0646\u062f \u0645\u06cc \u0628\u0627\u0634\u062f \u0648 \u0633\u0628\u0628 \u067e\u0627\u06cc\u06cc\u0646 \u0622\u0648\u0631\u062f\u0646 \u0645\u06cc\u0632\u0627\u0646 \u06af\u0633\u062a\u0631\u062f\u06af\u06cc \u06af\u0631\u0645\u0627\u06cc\u06cc \u0645\u0648\u0627\u062f \u0645\u06cc \u0634\u0648\u062f. \u0627\u0641\u0632\u0648\u0646 \u0628\u0631 \u0627\u06cc\u0646 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u0627\u062f\u0647 \u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0633\u0628\u0628 \u062f\u0631\u062e\u0634\u0627\u0646\u06cc\u060c \u0632\u06cc\u0628\u0627\u06cc\u06cc \u0648 \u062c\u0644\u0627\u06cc\u06cc \u062e\u0627\u0631\u0642 \u0627\u0644\u0639\u0627\u062f\u0647 \u0633\u0631\u0627\u0645\u06cc\u06a9 \u0647\u0627\u060c \u06a9\u0627\u0634\u06cc \u0647\u0627 \u0648 \u0638\u0631\u0641 \u0647\u0627\u06cc \u0644\u0639\u0627\u0628 \u062f\u0627\u0631 \u0645\u06cc \u0634\u0648\u062f \u0648 \u062c\u0630\u0627\u0628\u06cc\u062a \u0645\u0636\u0627\u0639\u0641\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0622\u0646\u0647\u0627 \u0628\u0647 \u0627\u0631\u0645\u063a\u0627\u0646 \u0645\u06cc \u0622\u0648\u0631\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A7%D8%B3%D8%AA%D9%81%D8%A7%D8%AF%D9%87_%D8%A7%D8%B2_%D8%A7%DB%8C%D9%86_%D9%85%D8%A7%D8%AF%D9%87_%D8%B4%D9%80%D9%80%DB%8C%D9%85%DB%8C%D8%A7%DB%8C%DB%8C_%D8%AF%D8%B1_%D8%AD%D8%B4%D8%B1%D9%87_%DA%A9%D8%B4%DB%8C\"><\/span><span style=\"color: #ff9900;\">\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062f\u0631 \u062d\u0634\u0631\u0647 \u06a9\u0634\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u06a9\u0634\u0648\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f9\u06f4\u06f8 \u0628\u0631\u0627\u06cc \u0628\u0627\u0631 \u0646\u062e\u0633\u062a \u062f\u0631 \u062f\u0646\u06cc\u0627\u060c\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u0631\u0627 \u0628\u0647 \u0633\u0627\u0646 \u06cc\u06a9 \u062d\u0634\u0631\u0647 \u06a9\u0634 \u0628\u0631\u0627\u06cc \u0645\u0647\u0627\u0631 \u0645\u0648\u0631\u0686\u0647 \u0647\u0627\u060c \u0645\u0648\u0631\u06cc\u0627\u0646\u0647 \u0647\u0627\u060c \u06a9\u06a9 \u0647\u0627\u060c \u0633\u0648\u0633\u06a9 \u0647\u0627 \u0648 \u062e\u06cc\u0644\u06cc \u0627\u0632 \u062c\u0627\u0646\u0648\u0631 \u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0628\u0647 \u06a9\u0627\u0631 \u0628\u0631\u062f\u0646\u062f. \u062f\u0644\u06cc\u0644 \u0622\u0646 \u06a9\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u062c\u0647\u062a \u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u0646 \u062d\u0634\u0631\u0627\u062a \u062e\u0627\u0646\u06af\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u062f \u0622\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0632\u06cc\u0627\u0646 \u0648 \u0639\u0627\u0631\u0636\u0647 \u0627\u06cc \u0628\u0631\u0627\u06cc \u062a\u0646\u062f\u0631\u0633\u062a\u06cc \u0622\u062f\u0645 \u0647\u0627 \u0646\u062f\u0627\u0631\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u06cc\u06a9 \u0634\u0631\u0646\u06af \u0645\u0639\u062f\u0647 \u0628\u0647 \u062d\u0633\u0627\u0628 \u0645\u06cc \u0622\u06cc\u062f \u06a9\u0647 \u062a\u0627\u062b\u06cc\u0631\u0627\u062a \u0622\u0646\u0627\u0628\u0648\u0644\u06cc\u0633\u0645 \u0628\u0631 \u0631\u0648\u06cc \u062d\u0634\u0631\u0627\u062a \u062f\u0627\u0631\u062f \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u067e\u0648\u062f\u0631 \u062e\u0634\u06a9 \u0622\u0646 \u0631\u0627 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0633\u0627\u06cc\u06cc\u062f\u0646 \u0633\u062a\u0648\u0646 \u0641\u0642\u0631\u0627\u062a \u062d\u0634\u0631\u0627\u062a \u0628\u0647 \u06a9\u0627\u0631 \u0645\u06cc \u0628\u0631\u0646\u062f. \u0633\u0648\u0633\u06a9 \u0628\u0639\u062f \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0632\u0647\u0631 \u0622\u0644\u0648\u062f \u0634\u062f \u0641\u0648\u0631\u0627 \u0646\u0645\u06cc \u0645\u06cc\u0631\u062f \u0648 \u0628\u0627 \u0634\u062a\u0627\u0628 \u06a9\u0645\u06cc \u0628\u0647 \u062e\u0627\u0646\u0647 \u062e\u0648\u062f \u0628\u0627\u0632\u06af\u0634\u062a\u0647 \u0648 \u0647\u0645\u0627\u0646 \u062c\u0627 \u0645\u06cc \u0645\u06cc\u0631\u062f.<\/p>\n<p style=\"text-align: justify;\">\u0627\u0645\u0627 \u0645\u0633\u0626\u0644\u0647 \u0686\u0634\u0645\u06af\u06cc\u0631 \u0627\u06cc\u0646 \u0642\u0636\u06cc\u0647 \u0622\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0632\u0645\u0627\u0646\u06cc \u0633\u0648\u0633\u06a9 \u062f\u0631 \u062e\u0627\u0646\u0647 \u062e\u0648\u062f \u062c\u0627\u0646 \u0645\u06cc \u062f\u0647\u062f \u062a\u0639\u0630\u06cc\u0647 \u062f\u06cc\u06af\u0631 \u0633\u0648\u0633\u06a9 \u0647\u0627\u06cc \u0645\u06cc \u0634\u0648\u062f \u0648 \u0628\u062f\u06cc\u0646 \u0639\u0644\u062a \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0628\u0647 \u0628\u062f\u0646 \u0622\u0646\u0647\u0627 \u0646\u06cc\u0632 \u0633\u0631\u0627\u06cc\u062a \u0645\u06cc \u06a9\u0646\u062f \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0647\u0645\u0647 \u0622\u0646\u0647\u0627 \u0645\u06cc \u0645\u06cc\u0631\u0646\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%B3%D8%A7%D8%AE%D8%AA_%D9%85%D9%88%D8%A7%D8%AF_%D8%B6%D8%AF_%D8%A2%D8%AA%D8%B4_%D8%A8%D9%87_%D9%88%D8%B3%DB%8C%D9%84%D9%87_%D8%A7%DB%8C%D9%86_%D9%85%D8%A7%D8%AF%D9%87_%D8%B4%D9%80%D9%80%DB%8C%D9%85%DB%8C%D8%A7%DB%8C%DB%8C\"><\/span><span style=\"color: #ff9900;\">\u0633\u0627\u062e\u062a \u0645\u0648\u0627\u062f \u0636\u062f \u0622\u062a\u0634 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u0640\u0640\u06cc\u0645\u06cc\u0627\u06cc\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0646\u0645\u06a9 \u0647\u0627\u06cc \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062d\u0627\u0648\u06cc \u0630\u0631\u0627\u062a\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0647\u0646\u06af\u0627\u0646 \u062f\u0631\u06cc\u0627\u0641\u062a \u06af\u0631\u0645\u0627 \u06cc\u0627 \u0627\u0646\u0631\u0698\u06cc \u0627\u0632 \u062e\u0648\u062f \u0622\u0628 \u062a\u0631\u0627\u0648\u0634 \u0645\u06cc \u06a9\u0646\u0646\u062f \u0648 \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0627\u0634\u062a\u0639\u0627\u0644 \u0648 \u0622\u062a\u0634 \u0633\u0648\u0632\u06cc \u0631\u0627 \u06a9\u0645 \u0645\u06cc \u06a9\u0646\u062f. \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0633\u0626\u0644\u0647 \u062f\u0642\u062a \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u062d\u0627\u0648\u06cc \u0642\u0627\u0631\u0686 \u06a9\u0634\u06cc \u062e\u06cc\u0644\u06cc \u062e\u0641\u06cc\u0641\u06cc \u0627\u0633\u062a \u0648 \u062f\u0631 \u067e\u0631\u0648\u0633\u0647 \u0627\u06cc\u062c\u0627\u062f \u062d\u0634\u0631\u0647 \u0648 \u0645\u0648\u0631\u0686\u0647 \u06a9\u0634 \u0647\u0627 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u062f\u0627\u0631\u062f.<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%A7%D8%B5_%D9%85%D9%87%D9%85_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%AF%D8%B1_%D9%85%D9%88%D8%A7%D8%AF_%D8%BA%D8%B0%D8%A7%DB%8C%DB%8C\"><\/span><span style=\"color: #ff9900;\">\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0633\u0627\u062e\u062a \u062e\u0648\u0631\u0627\u06a9\u06cc \u0647\u0627\u06cc \u0645\u062a\u0646\u0648\u0639 \u06a9\u0627\u0631\u0628\u0631\u062f \u0648\u0633\u06cc\u0639\u06cc \u062f\u0627\u0631 . \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062a\u0646\u062f\u0631\u0633\u062a\u06cc \u0628\u062f\u0646 \u062e\u06cc\u0644\u06cc \u0633\u0648\u062f\u0645\u0646\u062f \u0627\u0633\u062a \u0648 \u062e\u0648\u0627\u0635 \u0622\u0646\u062a\u06cc \u0627\u06a9\u0633\u06cc\u062f\u0627\u0646\u06cc \u0627\u0646 \u062e\u06cc\u0644\u06cc \u062a\u0648\u0627\u0646\u0645\u0646\u062f \u0645\u06cc \u0628\u0627\u0634\u062f. \u0628\u0639\u0636\u06cc \u0627\u0632 \u062e\u0648\u0631\u0627\u06a9\u06cc \u0647\u0627 \u0648 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u06a9\u0647 \u062d\u0627\u0648\u06cc \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u06cc \u0628\u0627\u0634\u0646\u062f \u0634\u0627\u0645\u0644: \u0628\u0627\u062f\u0627\u0645\u060c \u0628\u0631\u0646\u062c \u0633\u0641\u06cc\u062f\u060c \u0634\u0631\u0627\u0628\u060c \u0622\u0628\u062c\u0648\u060c \u0645\u0648\u0632 \u062e\u0627\u0645\u060c \u0633\u06cc\u0628\u060c \u0628\u0627\u062f\u0627\u0645 \u0632\u0645\u06cc\u0646\u06cc \u0648 &#8230;<\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AE%D9%88%D8%A7%D8%B5_%D8%B6%D8%AF_%D8%B3%D8%B1%D8%B7%D8%A7%D9%86%DB%8C_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9\"><\/span><span style=\"color: #ff9900;\">\u062e\u0648\u0627\u0635 \u0636\u062f \u0633\u0631\u0637\u0627\u0646\u06cc \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u0645\u0637\u0627\u0628\u0642 \u06cc\u06a9\u06cc \u0627\u0632 \u067e\u0698\u0648\u0647\u0634\u0627\u062a \u062f\u0631 \u0633\u0627\u0644 \u06f2\u06f0\u06f0\u06f9 \u0627\u06cc\u0646 \u0645\u0633\u0626\u0644\u0647 \u0631\u0648\u0634\u0646 \u0634\u062f \u06a9\u0647 \u0627\u062b\u0631 \u0628\u062e\u0634\u06cc \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u0628\u0631 \u0631\u0648\u06cc \u06a9\u0645 \u06a9\u0631\u062f\u0646 \u0633\u0644\u0648\u0644 \u0647\u0627\u06cc \u0633\u0631\u0637\u0627\u0646\u06cc \u0648\u0627\u0642\u0639\u06cc\u062a \u062f\u0627\u0631\u062f \u0648 \u0647\u0631 \u0686\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0645\u0635\u0631\u0641\u06cc \u0622\u0646 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0627\u0634\u062f \u0627\u06cc\u0646 \u0627\u062b\u0631\u0628\u062e\u0634\u06cc \u0647\u0645 \u0628\u0627\u0644\u0627\u062a\u0631 \u0645\u06cc \u0631\u0648\u062f.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A7%DB%8C%D9%86_%D9%86%D9%88%D8%B9_%D9%85%D8%A7%D8%AF%D9%87_%D8%B4%DB%8C%D9%85%DB%8C%D8%A7%DB%8C%DB%8C_%D9%88_%D9%82%D8%B7%D8%B1%D9%87_%DA%AF%D9%88%D8%B4\"><\/span><span style=\"color: #ff9900;\">\u0627\u06cc\u0646 \u0646\u0648\u0639 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0648 \u0642\u0637\u0631\u0647 \u06af\u0648\u0634<\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062e\u0627\u0635\u06cc\u062a \u0639\u0641\u0648\u0646\u062a \u0632\u0627\u06cc\u06cc \u0645\u0646\u062d\u0635\u0631 \u0628\u0647 \u0641\u0631\u062f \u0648 \u0648\u06cc\u0698\u0647 \u0627\u06cc \u062f\u0627\u0631\u062f \u0648 \u0645\u06cc \u062a\u0648\u0627\u0646 \u062c\u0647\u062a \u0645\u0639\u0627\u0644\u062c\u0647 \u0639\u0641\u0648\u0646\u062a \u0648 \u0686\u0631\u06a9 \u0647\u0627\u06cc \u06af\u0648\u0634 \u0622\u0646 \u0631\u0627 \u0628\u06a9\u0627\u0631 \u0628\u0631\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a \u062f\u0631 \u0633\u0627\u062e\u062a \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0641\u0631\u0622\u0648\u0631\u062f\u0647 \u0647\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc \u0634\u0648\u062f. \u062f\u0642\u062a \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0628\u06a9\u0627\u0631\u06af\u06cc\u0631\u06cc \u062e\u0648\u062f\u0633\u0631\u0627\u0646\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0628\u0647 \u0647\u06cc\u0686 \u0639\u0646\u0648\u0627\u0646 \u060c \u062a\u062d\u062a \u0647\u06cc\u0686 \u0634\u0631\u0627\u06cc\u0637\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u062f\u0627\u062f\u0647 \u0646\u0645\u06cc \u0634\u0648\u062f.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/nanotechshimi.ir\/blog\/wp-content\/uploads\/2021\/04\/\u062e\u0648\u0627\u0635-\u0645\u0647\u0645-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-\u062f\u0631-\u0635\u0646\u0627\u06cc\u0639.png\"><img loading=\"lazy\" class=\"alignnone wp-image-84 \" src=\"http:\/\/nanotechshimi.ir\/blog\/wp-content\/uploads\/2021\/04\/\u062e\u0648\u0627\u0635-\u0645\u0647\u0645-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-\u062f\u0631-\u0635\u0646\u0627\u06cc\u0639.png\" alt=\"\" width=\"521\" height=\"677\" srcset=\"https:\/\/nanotechshimi.ir\/blog\/wp-content\/uploads\/2021\/04\/\u062e\u0648\u0627\u0635-\u0645\u0647\u0645-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-\u062f\u0631-\u0635\u0646\u0627\u06cc\u0639.png 560w, https:\/\/nanotechshimi.ir\/blog\/wp-content\/uploads\/2021\/04\/\u062e\u0648\u0627\u0635-\u0645\u0647\u0645-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-\u062f\u0631-\u0635\u0646\u0627\u06cc\u0639-231x300.png 231w\" sizes=\"(max-width: 521px) 100vw, 521px\" \/><\/a><\/p>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B9%D8%B6%DB%8C_%D8%A7%D8%B2_%DA%A9%D8%A7%D8%B1%D8%A8%D8%B1%D8%AF_%D9%87%D8%A7%DB%8C_%D8%B9%D9%85%D8%AF%D9%87_%D8%A7%D8%B3%DB%8C%D8%AF_%D8%A8%D9%88%D8%B1%DB%8C%DA%A9_%D8%B9%D8%A8%D8%A7%D8%B1%D8%AA%D9%86%D8%AF_%D8%A7%D8%B2\"><\/span><span style=\"color: #ff9900;\">\u0628\u0639\u0636\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0628\u0631\u062f \u0647\u0627\u06cc \u0639\u0645\u062f\u0647 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">\u2022\u0627\u0632 \u062e\u0648\u0627\u0635 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646 \u0628\u0647 \u0645\u06cc\u06a9\u0631\u0648\u0628 \u06a9\u0634\u06cc \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f.<br \/>\n\u2022\u0645\u0630\u0627\u0628 \u06a9\u0646\u0646\u062f\u0647 \u0646\u06cc\u0631\u0648\u0645\u0646\u062f \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 \u062c\u0648\u0634\u06a9\u0627\u0631\u06cc<br \/>\n\u2022\u0633\u0627\u062e\u062a \u0634\u0648\u06cc\u0646\u062f\u0647 \u062c\u0627\u062a \u0648 \u0645\u0648\u0627\u062f \u0634\u0648\u06cc\u0646\u062f\u0647<br \/>\n\u2022\u062a\u0645\u0647\u06cc\u062f \u0648 \u0633\u0627\u062e\u062a \u0636\u062f \u06cc\u062e<br \/>\n\u2022\u0628\u0631\u0627\u06cc \u0686\u0631\u0645 \u0633\u0627\u0632\u06cc \u0646\u06cc\u0632 \u06a9\u0627\u0631\u0628\u0631\u062f \u0648\u06cc\u0698\u0647 \u0627\u06cc \u062f\u0627\u0631\u062f<br \/>\n\u2022\u0645\u0648\u062b\u0631 \u062f\u0631 \u062e\u06cc\u0644\u06cc \u0627\u0632 \u06a9\u0648\u062f \u0647\u0627\u06cc \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #008000;\">\u0633\u0627\u06cc\u062a \u0646\u0627\u0646\u0648 \u062a\u06a9 \u0634\u06cc\u0645\u06cc<\/span> \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u0646\u062f\u0647 <span style=\"color: #ff6600;\"><a style=\"color: #ff6600;\" href=\"http:\/\/nanotechshimi.ir\/%d8%a7%d8%b3%db%8c%d8%af%d9%87%d8%a7\/\" target=\"_blank\" rel=\"noopener\">\u0627\u0646\u0648\u0627\u0639 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0622\u0632\u0645\u0627\u06cc\u0634\u06af\u0627\u0647\u06cc<\/a><\/span><\/strong> \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0645\u06cc \u062a\u0648\u0627\u0646 \u0641\u0631\u0627\u0648\u0631\u062f\u0647 \u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u0633\u0627\u06cc\u062a \u062a\u0647\u06cc\u0647 \u0646\u0645\u0648\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639\u060c\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u06cc\u06a9 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0634\u0646\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0635\u0648\u0631\u062a \u062c\u0627\u0645\u062f \u0647\u0645 \u0645\u06cc \u0628\u0627\u0634\u062f. \u0631\u0646\u06af \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0633\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u060c \u062f\u0627\u0631\u0627\u06cc \u0637\u0639\u0645\u06cc \u062a\u0644\u062e \u0648 \u0628\u06cc \u0628\u0648 \u0645\u06cc \u0628\u0627\u0634\u062f.\u200c \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0645\u0639\u0645\u0648\u0644\u0627 \u0627\u0633\u06cc\u062f\u06cc \u0636\u0639\u06cc\u0641 \u0628\u0647 \u0634\u0645\u0627\u0631 \u0645\u06cc \u0622\u06cc\u062f \u0648 \u0646\u0645\u06a9 \u0647\u0627\u06cc \u062d\u0627\u0648\u06cc \u0633\u062f\u06cc\u0645 \u062f\u0627\u0631\u062f \u06a9\u0647 &hellip;<\/p>\n","protected":false},"author":1,"featured_media":83,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 | \u0633\u0627\u062e\u062a \u0645\u0648\u0627\u062f \u0636\u062f \u0622\u062a\u0634 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9<\/title>\n<meta name=\"description\" content=\"\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u06cc\u06a9 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0634\u0646\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0635\u0648\u0631\u062a \u062c\u0627\u0645\u062f \u0647\u0645 \u0645\u06cc \u0628\u0627\u0634\u062f. \u0631\u0646\u06af \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0633\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u0648 \u062f\u0627\u0631\u0627\u06cc \u0637\u0639\u0645\u06cc \u062a\u0644\u062e \u0648 \u0628\u06cc \u0628\u0648 \u0645\u06cc \u0628\u0627\u0634\u062f.\u200c\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nanotechshimi.ir\/blog\/\u062e\u0648\u0627\u0635-\u0645\u0647\u0645-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-\u062f\u0631-\u0635\u0646\u0627\u06cc\u0639\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062e\u0648\u0627\u0635 \u0645\u0647\u0645 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u062f\u0631 \u0635\u0646\u0627\u06cc\u0639 | \u0633\u0627\u062e\u062a \u0645\u0648\u0627\u062f \u0636\u062f \u0622\u062a\u0634 \u0628\u0647 \u0648\u0633\u06cc\u0644\u0647 \u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9\" \/>\n<meta property=\"og:description\" content=\"\u0627\u0633\u06cc\u062f \u0628\u0648\u0631\u06cc\u06a9 \u06cc\u06a9 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0634\u0646\u0627\u062e\u062a\u0647 \u0634\u062f\u0647 \u0645\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0635\u0648\u0631\u062a \u062c\u0627\u0645\u062f \u0647\u0645 \u0645\u06cc \u0628\u0627\u0634\u062f. \u0631\u0646\u06af \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0633\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u0648 \u062f\u0627\u0631\u0627\u06cc \u0637\u0639\u0645\u06cc \u062a\u0644\u062e \u0648 \u0628\u06cc \u0628\u0648 \u0645\u06cc \u0628\u0627\u0634\u062f.\u200c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nanotechshimi.ir\/blog\/\u062e\u0648\u0627\u0635-\u0645\u0647\u0645-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-\u062f\u0631-\u0635\u0646\u0627\u06cc\u0639\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0634\u0631\u06a9\u062a \u0646\u0627\u0646\u0648 \u062a\u06a9 \u0634\u06cc\u0645\u06cc\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-24T11:23:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-31T09:52:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nanotechshimi.ir\/blog\/wp-content\/uploads\/2021\/04\/\u062e\u0648\u0627\u0635-\u0627\u0633\u06cc\u062f-\u0628\u0648\u0631\u06cc\u06a9-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647\u200c\u0634\u062f\u0647 \u0628\u062f\u0633\u062a\">\n\t<meta name=\"twitter:data1\" content=\"modir\">\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u0642\u0631\u06cc\u0628\u06cc \u0628\u0631\u0627\u06cc \u062e\u0648\u0627\u0646\u062f\u0646\">\n\t<meta name=\"twitter:data2\" content=\"0 \u062f\u0642\u06cc\u0642\u0647\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nanotechshimi.ir\/blog\/#website\",\"url\":\"https:\/\/nanotechshimi.ir\/blog\/\",\"name\":\"\\u0634\\u0631\\u06a9\\u062a \\u0646\\u0627\\u0646\\u0648 \\u062a\\u06a9 \\u0634\\u06cc\\u0645\\u06cc\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/nanotechshimi.ir\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#primaryimage\",\"inLanguage\":\"fa-IR\",\"url\":\"https:\/\/nanotechshimi.ir\/blog\/wp-content\/uploads\/2021\/04\/\\u062e\\u0648\\u0627\\u0635-\\u0627\\u0633\\u06cc\\u062f-\\u0628\\u0648\\u0631\\u06cc\\u06a9-.jpg\",\"width\":500,\"height\":448},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#webpage\",\"url\":\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/\",\"name\":\"\\u062e\\u0648\\u0627\\u0635 \\u0645\\u0647\\u0645 \\u0627\\u0633\\u06cc\\u062f \\u0628\\u0648\\u0631\\u06cc\\u06a9 \\u062f\\u0631 \\u0635\\u0646\\u0627\\u06cc\\u0639 | \\u0633\\u0627\\u062e\\u062a \\u0645\\u0648\\u0627\\u062f \\u0636\\u062f \\u0622\\u062a\\u0634 \\u0628\\u0647 \\u0648\\u0633\\u06cc\\u0644\\u0647 \\u0627\\u0633\\u06cc\\u062f \\u0628\\u0648\\u0631\\u06cc\\u06a9\",\"isPartOf\":{\"@id\":\"https:\/\/nanotechshimi.ir\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/#primaryimage\"},\"datePublished\":\"2021-04-24T11:23:55+00:00\",\"dateModified\":\"2021-07-31T09:52:46+00:00\",\"author\":{\"@id\":\"https:\/\/nanotechshimi.ir\/blog\/#\/schema\/person\/8d39705c8277172b13dc7fd025540135\"},\"description\":\"\\u0627\\u0633\\u06cc\\u062f \\u0628\\u0648\\u0631\\u06cc\\u06a9 \\u06cc\\u06a9 \\u0645\\u0627\\u062f\\u0647 \\u0634\\u06cc\\u0645\\u06cc\\u0627\\u06cc\\u06cc \\u0634\\u0646\\u0627\\u062e\\u062a\\u0647 \\u0634\\u062f\\u0647 \\u0645\\u06cc \\u0628\\u0627\\u0634\\u062f \\u06a9\\u0647 \\u0628\\u0635\\u0648\\u0631\\u062a \\u062c\\u0627\\u0645\\u062f \\u0647\\u0645 \\u0645\\u06cc \\u0628\\u0627\\u0634\\u062f. \\u0631\\u0646\\u06af \\u0627\\u06cc\\u0646 \\u0645\\u0627\\u062f\\u0647 \\u0634\\u06cc\\u0645\\u06cc\\u0627\\u06cc\\u06cc \\u0633\\u0641\\u06cc\\u062f \\u0628\\u0648\\u062f\\u0647 \\u0648 \\u062f\\u0627\\u0631\\u0627\\u06cc \\u0637\\u0639\\u0645\\u06cc \\u062a\\u0644\\u062e \\u0648 \\u0628\\u06cc \\u0628\\u0648 \\u0645\\u06cc \\u0628\\u0627\\u0634\\u062f.\\u200c\",\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nanotechshimi.ir\/blog\/%d8%ae%d9%88%d8%a7%d8%b5-%d9%85%d9%87%d9%85-%d8%a7%d8%b3%db%8c%d8%af-%d8%a8%d9%88%d8%b1%db%8c%da%a9-%d8%af%d8%b1-%d8%b5%d9%86%d8%a7%db%8c%d8%b9\/\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/nanotechshimi.ir\/blog\/#\/schema\/person\/8d39705c8277172b13dc7fd025540135\",\"name\":\"modir\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/nanotechshimi.ir\/blog\/#personlogo\",\"inLanguage\":\"fa-IR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/afc7e8792530a38b66c2b6ea15c18614?s=96&d=mm&r=g\",\"caption\":\"modir\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/posts\/82"}],"collection":[{"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/comments?post=82"}],"version-history":[{"count":3,"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/posts\/82\/revisions"}],"predecessor-version":[{"id":255,"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/posts\/82\/revisions\/255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/media\/83"}],"wp:attachment":[{"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/media?parent=82"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/categories?post=82"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nanotechshimi.ir\/blog\/wp-json\/wp\/v2\/tags?post=82"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}